{"id":8392,"date":"2025-06-27T11:53:46","date_gmt":"2025-06-27T09:53:46","guid":{"rendered":"https:\/\/museidartemendrisiotto.ch\/?p=8392"},"modified":"2025-06-27T11:53:46","modified_gmt":"2025-06-27T09:53:46","slug":"le-museo-vincenzo-vela","status":"publish","type":"post","link":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/","title":{"rendered":"Le Museo Vincenzo Vela"},"content":{"rendered":"<h2>Vela apr\u00e8s son retour dans la r\u00e9gion du Mendrisiotto en 1867<\/h2>\n<p>Vincenzo Vela retourna d\u00e9finitivement \u00e0 Ligornetto en 1867. Parall\u00e8lement \u00e0 ses activit\u00e9s artistiques, il se lan\u00e7a dans un combat politique et social en faveur de ses concitoyens et des couches les plus d\u00e9favoris\u00e9es de la population tessinoise.<br \/>\nPla\u00e7ant sa condition de citoyen suisse avant m\u00eame son statut d&rsquo;artiste, le sculpteur fut membre du Conseil cantonal de l&rsquo;instruction publique de 1862 \u00e0 1877, o\u00f9 il \u0153uvra essentiellement au soutien des \u00e9coles de dessin, puis il fut d\u00e9put\u00e9 du Grand Conseil de 1877 et 1881. En outre, toujours dans le domaine de l&rsquo;\u00e9ducation, Vela mit tout en \u0153uvre pour que soit cr\u00e9\u00e9e une \u00e9cole des beaux-arts dans le Tessin, malheureusement en vain. R\u00e9publicain convaincu et \u00ab inspir\u00e9 par des principes lib\u00e9raux \u00bb, il a toujours d\u00e9fendu ses id\u00e9aux politiques. Il fut membre de nombreuses soci\u00e9t\u00e9s d&rsquo;aide mutuelle et fit preuve d&rsquo;une grande g\u00e9n\u00e9rosit\u00e9 qui se prolongea m\u00eame apr\u00e8s sa mort \u00e0 travers le legs de son fils Spartaco. Gr\u00e2ce \u00e0 lui, Ligornetto fut en mesure d&rsquo;am\u00e9liorer ses infrastructures publiques. Son haut-relief Les victimes du travail, librement r\u00e9alis\u00e9 en 1882, s&rsquo;inspira des ouvriers morts sur le chantier de construction du tunnel ferroviaire du Saint-Gothard. \u00c0 travers cette \u0153uvre, Vincenzo Vela signa un v\u00e9ritable manifeste pour les droits sociaux et humanitaires.<br \/>\nSon action en faveur des personnes les plus d\u00e9favoris\u00e9es n&rsquo;est pas sans rappeler l&rsquo;engagement d&rsquo;un autre philanthrope, le comte Alfonso Turconi, dont il sculpta le portrait. Ce dernier fit un legs qui permit \u00e0 Mendrisio de fonder ce qui devint plus tard l&rsquo;h\u00f4pital de la Beata Vergine, aujourd&rsquo;hui si\u00e8ge de l&rsquo;Acad\u00e9mie d&rsquo;architecture de l&rsquo;Universit\u00e9, \u00e0 c\u00f4t\u00e9 de laquelle se dresse le Teatro dell&rsquo;architettura.<\/p>\n<h2>La Villa Vela dans la \u00ab Campagnadorna \u00bb de la moiti\u00e9 du XIXe si\u00e8cle<\/h2>\n<p>Entre 1862 et 1866, une batisse imposante fut \u00e9rig\u00e9e sur un vaste terrain situ\u00e9 sur une colline au nord d&rsquo;un village rural. Con\u00e7ue par Cipriano Ajmetti, architecte des ducs de G\u00eanes, elle fut construite par l&rsquo;architecte Isidoro Spinelli di Sagno. Cet \u00e9difice majestueux -rapidement rebaptis\u00e9 \u00ab Panth\u00e9on Vela \u00bb-, qui servait \u00e0 la fois de r\u00e9sidence \u00e0 la famille Vela, d&rsquo;atelier et de galerie des pl\u00e2tres du sculpteur, inspirait un m\u00e9lange de respect et de crainte dans la Campagnadorna de la moiti\u00e9 du XIXe si\u00e8cle. En r\u00e9alit\u00e9, Vincenzo Vela ouvrait fraternellement les portes de sa demeure et de sa salle \u00e0 manger \u00e0 quiconque se trouvait dans le besoin. Ce n&rsquo;est donc pas un hasard si \u00e0 sa mort, \u00e0 travers le legs de Spartaco, la villa devint le premier mus\u00e9e public du Tessin (1896). Ce g\u00e9nie artistique aux humbles racines campagnardes ne n\u00e9gligeait pas le travail de la terre, ce qui le rapprochait de la plupart de ses concitoyens.<br \/>\nC&rsquo;est en ces termes, alors qu&rsquo;il r\u00e9sidait encore \u00e0 Turin, qu&rsquo;il d\u00e9crivit dans une lettre son s\u00e9jour pass\u00e9 \u00e0 Ligornetto pendant la saison automnale : \u00ab au cours de ces deux mois de vacances, je ne suis plus un artiste, mais un paysan et un chasseur \u00bb. Il vouait d&rsquo;ailleurs une passion d\u00e9mesur\u00e9e pour ses chiens de chasse. Il poss\u00e9dait \u00e9galement une cave \u00e0 vin \u00e0 Rancate, o\u00f9 se dresse aujourd&rsquo;hui la Pinacoteca cantonale Giovanni Z\u00fcst. Il y conservait un \u00ab nectar \u00bb qu&rsquo;il aimait partager avec ses amis et coll\u00e8gues.<br \/>\nUn fait troubla toutefois ce cadre globalement idyllique : la nuit du 6 mars 1867, des inconnus tir\u00e8rent des coups de fusil sur la villa \u00e0 des fins d&rsquo;intimidation. Il s&rsquo;agit sans doute d&rsquo;un avertissement dont on ne connut jamais les motifs.<\/p>\n<h2>La tradition de la sculpture dans le Mendrisiotto et les carri\u00e8res de marbre<\/h2>\n<p>Arzo, Besazio, Viggi\u00f9&#8230; sont des communes frontali\u00e8res proches de Ligornetto, c\u00e9l\u00e8bres pour leurs carri\u00e8res et leurs pierres de diverses qualit\u00e9s. Elles ont vu na\u00eetre de nombreux tailleurs de pierre, ornemanistes et sculpteurs qui, apr\u00e8s avoir pratiqu\u00e9 l&rsquo;art du travail de la pierre &#8211; souvent \u00e0 l&rsquo;\u00e9tranger -, revenaient sur leur terre pour y laisser de pr\u00e9cieuses traces de leur ma\u00eetrise. Parmi ceux-ci, mentionnons notamment Apollonio Pessina, conservateur de notre mus\u00e9e pendant pr\u00e8s de quarante ans. Ce fut \u00e9galement le cas de Vincenzo Vela qui, d\u00e8s l&rsquo;enfance, fut initi\u00e9 au m\u00e9tier de tailleur de pierre dans les carri\u00e8res voisines puis, vers 1834, rejoignit son fr\u00e8re a\u00een\u00e9 Lorenzo, sculpteur ornemaniste \u00e0 Milan, afin de poursuivre son apprentissage dans la carri\u00e8re de la cath\u00e9drale du Duomo. C&rsquo;est dans ce contexte et avec ces origines modestes que na\u00eet le talent artistique du sculpteur, qui se nourrit ensuite de la longue tradition culturelle italienne.<\/p>\n<p>Les \u0153uvres expos\u00e9es dans sa gypsoth\u00e8que se distinguent certainement des sculptures plus simples et \u00e9parses issues de la tradition ant\u00e9rieure ou contemporaine. Plut\u00f4t qu&rsquo;un lieu d&rsquo;autoc\u00e9l\u00e9bration, il s&rsquo;agit en r\u00e9alit\u00e9 d&rsquo;un espace accueillant de formation et d&rsquo;enrichissement personnel, ouvert au public d\u00e8s le d\u00e9but, ce que renfor\u00e7a le legs \u00e0 la Conf\u00e9d\u00e9ration suisse en vue d&rsquo;en faire un mus\u00e9e ou une \u00e9cole d&rsquo;art.<\/p>\n<p>Parmi les cr\u00e9ations expos\u00e9es, mentionnons l&rsquo;Ecce Homo, une r\u00e9plique en marbre de la sculpture veillant sur la d\u00e9pouille mortelle de Vela au cimeti\u00e8re de Ligornetto. Ce monument \u00e9rig\u00e9 par son fils Spartaco et d&rsquo;anciens \u00e9tudiants du ma\u00eetre, a \u00e9t\u00e9 restaur\u00e9 \u00e0 l&rsquo;occasion du bicentenaire de la naissance de ce dernier, gr\u00e2ce \u00e0 une aide importante de la ville de Mendrisio, o\u00f9 se dresse le Museo d&rsquo;arte.<\/p>\n<h2>La fronti\u00e8re qui a marqu\u00e9 l&rsquo;histoire de la r\u00e9gion du Mendrisiotto et de Vincenzo Vela<\/h2>\n<p>Ligornetto n&rsquo;est \u00e9loign\u00e9e que de quelques kilom\u00e8tres de l&rsquo;Italie. Comme souvent, la fronti\u00e8re fut davantage un point de rencontre et d&rsquo;\u00e9change qu&rsquo;une v\u00e9ritable ligne de s\u00e9paration, notamment aux yeux de Vincenzo Vela. En effet, celui-ci \u00e9tait un citoyen, artiste et patriote \u00e0 la fois suisse &#8211; son credo r\u00e9publicain et lib\u00e9ral le porta au front de la guerre du Sonderbund &#8211; et italien &#8211; en t\u00e9moignent sa participation volontaire aux mouvements li\u00e9s au Risorgimento et bien s\u00fbr son inspiration artistique. Pour lui, la fronti\u00e8re ne constituait aucune barri\u00e8re : \u00ab mes principes politiques sont d&rsquo;ordre universel et je prendrai toujours parti pour les peuples qui luttent pour leur ind\u00e9pendance vis-\u00e0-vis des \u00e9trangers et qui tentent d&rsquo;avancer sur la voie de la libert\u00e9 et du progr\u00e8s&#8230; \u00bb.<br \/>\nCe n&rsquo;est d&rsquo;ailleurs pas un hasard si l&rsquo;histoire de l&rsquo;unification de l&rsquo;Italie est pr\u00e9sent\u00e9e dans le salon principal de sa villa, sur le sol helv\u00e9tique.<br \/>\nDans la r\u00e9gion du Mendrisiotto, la ville fronti\u00e8re par excellence est Chiasso, porte m\u00e9ridionale de la \u00ab Via delle genti \u00bb. On y trouve le \u00ab m.a.x. museo \u00bb, inspir\u00e9 par l&rsquo;artiste zurichois Max Huber, pour qui la fronti\u00e8re \u00e9tait \u00e9galement un formidable espace de rencontre et d&rsquo;\u00e9change.<br \/>\nPour conclure sur un ton plus l\u00e9ger, mentionnons l&rsquo;anecdote selon laquelle Vela aimait se reposer dans un pavillon de chasse de sa propri\u00e9t\u00e9, o\u00f9 il s&rsquo;adonnait \u00e9galement au pi\u00e9geage des oiseaux, une pratique interdite en Suisse mais pas en Italie. En fait, ce pavillon se situait, \u00e0 quelques m\u00e8tres pr\u00e8s, dans le territoire italien, mais ne tombait pas sous le coup de l&rsquo;imposition douani\u00e8re&#8230; Ce petit subterfuge \u00e9tait peut-\u00eatre la fa\u00e7on des autorit\u00e9s du royaume d&rsquo;Italie de rendre hommage \u00e0 Vela pour sa participation aux luttes du Risorgimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vela apr\u00e8s son retour dans la r\u00e9gion du Mendrisiotto en 1867 Vincenzo Vela retourna d\u00e9finitivement \u00e0 Ligornetto en 1867. Parall\u00e8lement \u00e0 ses activit\u00e9s artistiques, il se lan\u00e7a dans un combat politique et social en faveur de ses concitoyens et des couches les plus d\u00e9favoris\u00e9es de la population tessinoise. Pla\u00e7ant sa condition de citoyen suisse avant &#8230; <a title=\"Le Museo Vincenzo Vela\" class=\"read-more\" href=\"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/\">Read more <span class=\"screen-reader-text\">Le Museo Vincenzo Vela<\/span><\/a><\/p>\n","protected":false},"author":9,"featured_media":8389,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[54],"tags":[69],"class_list":["post-8392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mam-fr","tag-attualita-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Musei d\u2019Arte del Mendrisiotto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Musei d\u2019Arte del Mendrisiotto\" \/>\n<meta property=\"og:description\" content=\"Vela apr\u00e8s son retour dans la r\u00e9gion du Mendrisiotto en 1867 Vincenzo Vela retourna d\u00e9finitivement \u00e0 Ligornetto en 1867. Parall\u00e8lement \u00e0 ses activit\u00e9s artistiques, il se lan\u00e7a dans un combat politique et social en faveur de ses concitoyens et des couches les plus d\u00e9favoris\u00e9es de la population tessinoise. Pla\u00e7ant sa condition de citoyen suisse avant ... Read more Le Museo Vincenzo Vela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/\" \/>\n<meta property=\"og:site_name\" content=\"Musei d\u2019Arte del Mendrisiotto\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-27T09:53:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/museidartemendrisiotto.ch\/wp-content\/uploads\/2025\/06\/selezione-rete-MAM-041-copia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rebecca.maspoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"rebecca.maspoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/\"},\"author\":{\"name\":\"rebecca.maspoli\",\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/#\\\/schema\\\/person\\\/07a2587aedb8d3a7d2ad98a08959a011\"},\"headline\":\"Le Museo Vincenzo Vela\",\"datePublished\":\"2025-06-27T09:53:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/\"},\"wordCount\":1318,\"publisher\":{\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/selezione-rete-MAM-041-copia-1.jpg\",\"keywords\":[\"Attualit\u00e0\"],\"articleSection\":[\"Musei d&#8217;Arte del Mendrisiotto\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/\",\"url\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/\",\"name\":\"- Musei d\u2019Arte del Mendrisiotto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/selezione-rete-MAM-041-copia-1.jpg\",\"datePublished\":\"2025-06-27T09:53:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/selezione-rete-MAM-041-copia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/selezione-rete-MAM-041-copia-1.jpg\",\"width\":900,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/le-museo-vincenzo-vela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Museo Vincenzo Vela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/#website\",\"url\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/\",\"name\":\"Musei d\u2019Arte del Mendrisiotto\",\"description\":\"La rete dei Musei d\u2019Arte del Mendrisiotto (MAM) si propone di rafforzare la visibilit\u00e0, promuovere la conoscenza dei musei del Mendrisiotto\",\"publisher\":{\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/#organization\",\"name\":\"Musei d\u2019Arte del Mendrisiotto\",\"url\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo_mam.png\",\"contentUrl\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo_mam.png\",\"width\":350,\"height\":250,\"caption\":\"Musei d\u2019Arte del Mendrisiotto\"},\"image\":{\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/museidartemendrisiotto.ch\\\/#\\\/schema\\\/person\\\/07a2587aedb8d3a7d2ad98a08959a011\",\"name\":\"rebecca.maspoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eb20f31dcf75e20617a614b0e85501b6ad78fb1a0795c54bd53ddff54b7b6a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eb20f31dcf75e20617a614b0e85501b6ad78fb1a0795c54bd53ddff54b7b6a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eb20f31dcf75e20617a614b0e85501b6ad78fb1a0795c54bd53ddff54b7b6a4?s=96&d=mm&r=g\",\"caption\":\"rebecca.maspoli\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Musei d\u2019Arte del Mendrisiotto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/","og_locale":"fr_FR","og_type":"article","og_title":"- Musei d\u2019Arte del Mendrisiotto","og_description":"Vela apr\u00e8s son retour dans la r\u00e9gion du Mendrisiotto en 1867 Vincenzo Vela retourna d\u00e9finitivement \u00e0 Ligornetto en 1867. Parall\u00e8lement \u00e0 ses activit\u00e9s artistiques, il se lan\u00e7a dans un combat politique et social en faveur de ses concitoyens et des couches les plus d\u00e9favoris\u00e9es de la population tessinoise. Pla\u00e7ant sa condition de citoyen suisse avant ... Read more Le Museo Vincenzo Vela","og_url":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/","og_site_name":"Musei d\u2019Arte del Mendrisiotto","article_published_time":"2025-06-27T09:53:46+00:00","og_image":[{"width":900,"height":415,"url":"https:\/\/museidartemendrisiotto.ch\/wp-content\/uploads\/2025\/06\/selezione-rete-MAM-041-copia-1.jpg","type":"image\/jpeg"}],"author":"rebecca.maspoli","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"rebecca.maspoli","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/#article","isPartOf":{"@id":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/"},"author":{"name":"rebecca.maspoli","@id":"https:\/\/museidartemendrisiotto.ch\/#\/schema\/person\/07a2587aedb8d3a7d2ad98a08959a011"},"headline":"Le Museo Vincenzo Vela","datePublished":"2025-06-27T09:53:46+00:00","mainEntityOfPage":{"@id":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/"},"wordCount":1318,"publisher":{"@id":"https:\/\/museidartemendrisiotto.ch\/#organization"},"image":{"@id":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/#primaryimage"},"thumbnailUrl":"https:\/\/museidartemendrisiotto.ch\/wp-content\/uploads\/2025\/06\/selezione-rete-MAM-041-copia-1.jpg","keywords":["Attualit\u00e0"],"articleSection":["Musei d&#8217;Arte del Mendrisiotto"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/","url":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/","name":"- Musei d\u2019Arte del Mendrisiotto","isPartOf":{"@id":"https:\/\/museidartemendrisiotto.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/#primaryimage"},"image":{"@id":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/#primaryimage"},"thumbnailUrl":"https:\/\/museidartemendrisiotto.ch\/wp-content\/uploads\/2025\/06\/selezione-rete-MAM-041-copia-1.jpg","datePublished":"2025-06-27T09:53:46+00:00","breadcrumb":{"@id":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/#primaryimage","url":"https:\/\/museidartemendrisiotto.ch\/wp-content\/uploads\/2025\/06\/selezione-rete-MAM-041-copia-1.jpg","contentUrl":"https:\/\/museidartemendrisiotto.ch\/wp-content\/uploads\/2025\/06\/selezione-rete-MAM-041-copia-1.jpg","width":900,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/museidartemendrisiotto.ch\/fr\/le-museo-vincenzo-vela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/museidartemendrisiotto.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Museo Vincenzo Vela"}]},{"@type":"WebSite","@id":"https:\/\/museidartemendrisiotto.ch\/#website","url":"https:\/\/museidartemendrisiotto.ch\/","name":"Musei d\u2019Arte del Mendrisiotto","description":"La rete dei Musei d\u2019Arte del Mendrisiotto (MAM) si propone di rafforzare la visibilit\u00e0, promuovere la conoscenza dei musei del Mendrisiotto","publisher":{"@id":"https:\/\/museidartemendrisiotto.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museidartemendrisiotto.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/museidartemendrisiotto.ch\/#organization","name":"Musei d\u2019Arte del Mendrisiotto","url":"https:\/\/museidartemendrisiotto.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/museidartemendrisiotto.ch\/#\/schema\/logo\/image\/","url":"https:\/\/museidartemendrisiotto.ch\/wp-content\/uploads\/2020\/06\/logo_mam.png","contentUrl":"https:\/\/museidartemendrisiotto.ch\/wp-content\/uploads\/2020\/06\/logo_mam.png","width":350,"height":250,"caption":"Musei d\u2019Arte del Mendrisiotto"},"image":{"@id":"https:\/\/museidartemendrisiotto.ch\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/museidartemendrisiotto.ch\/#\/schema\/person\/07a2587aedb8d3a7d2ad98a08959a011","name":"rebecca.maspoli","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8eb20f31dcf75e20617a614b0e85501b6ad78fb1a0795c54bd53ddff54b7b6a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8eb20f31dcf75e20617a614b0e85501b6ad78fb1a0795c54bd53ddff54b7b6a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8eb20f31dcf75e20617a614b0e85501b6ad78fb1a0795c54bd53ddff54b7b6a4?s=96&d=mm&r=g","caption":"rebecca.maspoli"}}]}},"_links":{"self":[{"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/posts\/8392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/comments?post=8392"}],"version-history":[{"count":1,"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/posts\/8392\/revisions"}],"predecessor-version":[{"id":8393,"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/posts\/8392\/revisions\/8393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/media\/8389"}],"wp:attachment":[{"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/media?parent=8392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/categories?post=8392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/museidartemendrisiotto.ch\/fr\/wp-json\/wp\/v2\/tags?post=8392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}